{"id":23,"count":10,"description":"","link":"https:\/\/advantageamerica.net\/es\/category\/video\/","name":"Video","slug":"video","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Video Archives - Advantage America Insurance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/advantageamerica.net\/es\/category\/video\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video Archives - Advantage America Insurance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/advantageamerica.net\/es\/category\/video\/\" \/>\n<meta property=\"og:site_name\" content=\"Advantage America Insurance\" \/>\n<meta property=\"og:image\" content=\"https:\/\/advantageamerica.net\/wp-content\/uploads\/2019\/06\/logofull-retina.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/advantageamerica.net\/category\/video\/\",\"url\":\"https:\/\/advantageamerica.net\/category\/video\/\",\"name\":\"Video Archives - Advantage America Insurance\",\"isPartOf\":{\"@id\":\"https:\/\/advantageamerica.net\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/advantageamerica.net\/category\/video\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/advantageamerica.net\/category\/video\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/advantageamerica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/advantageamerica.net\/#website\",\"url\":\"https:\/\/advantageamerica.net\/\",\"name\":\"Advantage America Insurance\",\"description\":\"Home, Auto and Business Insurance in Murrieta, CA\",\"publisher\":{\"@id\":\"https:\/\/advantageamerica.net\/#organization\"},\"alternateName\":\"Advantage America Insurance\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/advantageamerica.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/advantageamerica.net\/#organization\",\"name\":\"Advantage America Insurance\",\"alternateName\":\"Advantage America Insurance\",\"url\":\"https:\/\/advantageamerica.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/advantageamerica.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/advantageamerica.net\/wp-content\/uploads\/2019\/06\/logo-footer-1.png\",\"contentUrl\":\"https:\/\/advantageamerica.net\/wp-content\/uploads\/2019\/06\/logo-footer-1.png\",\"width\":300,\"height\":134,\"caption\":\"Advantage America Insurance\"},\"image\":{\"@id\":\"https:\/\/advantageamerica.net\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Video Archives - Advantage America Insurance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/advantageamerica.net\/es\/category\/video\/","og_locale":"es_MX","og_type":"article","og_title":"Video Archives - Advantage America Insurance","og_url":"https:\/\/advantageamerica.net\/es\/category\/video\/","og_site_name":"Advantage America Insurance","og_image":[{"width":1366,"height":595,"url":"https:\/\/advantageamerica.net\/wp-content\/uploads\/2019\/06\/logofull-retina.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/advantageamerica.net\/category\/video\/","url":"https:\/\/advantageamerica.net\/category\/video\/","name":"Video Archives - Advantage America Insurance","isPartOf":{"@id":"https:\/\/advantageamerica.net\/#website"},"breadcrumb":{"@id":"https:\/\/advantageamerica.net\/category\/video\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/advantageamerica.net\/category\/video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/advantageamerica.net\/"},{"@type":"ListItem","position":2,"name":"Video"}]},{"@type":"WebSite","@id":"https:\/\/advantageamerica.net\/#website","url":"https:\/\/advantageamerica.net\/","name":"Advantage America Insurance","description":"Home, Auto and Business Insurance in Murrieta, CA","publisher":{"@id":"https:\/\/advantageamerica.net\/#organization"},"alternateName":"Advantage America Insurance","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/advantageamerica.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/advantageamerica.net\/#organization","name":"Advantage America Insurance","alternateName":"Advantage America Insurance","url":"https:\/\/advantageamerica.net\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/advantageamerica.net\/#\/schema\/logo\/image\/","url":"https:\/\/advantageamerica.net\/wp-content\/uploads\/2019\/06\/logo-footer-1.png","contentUrl":"https:\/\/advantageamerica.net\/wp-content\/uploads\/2019\/06\/logo-footer-1.png","width":300,"height":134,"caption":"Advantage America Insurance"},"image":{"@id":"https:\/\/advantageamerica.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/advantageamerica.net\/es\/wp-json\/wp\/v2\/categories\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advantageamerica.net\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/advantageamerica.net\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/advantageamerica.net\/es\/wp-json\/wp\/v2\/posts?categories=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}